{"id":50,"count":38,"description":"Old games for old formats, for example Nintendo 8-bit (NES), Super Nintendo (SNES), Commodore Amiga, SEGA Mega Drive, arcade games and more.","link":"https:\/\/www.senses.se\/en\/gaming\/retro\/","name":"Retro","slug":"retro","taxonomy":"category","parent":29,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retro-arkiv - Senses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.senses.se\/en\/gaming\/retro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retro-arkiv - Senses\" \/>\n<meta property=\"og:description\" content=\"Old games for old formats, for example Nintendo 8-bit (NES), Super Nintendo (SNES), Commodore Amiga, SEGA Mega Drive, arcade games and more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.senses.se\/en\/gaming\/retro\/\" \/>\n<meta property=\"og:site_name\" content=\"Senses\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/gaming\\\/retro\\\/\",\"url\":\"https:\\\/\\\/www.senses.se\\\/en\\\/gaming\\\/retro\\\/\",\"name\":\"Retro-arkiv - Senses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/gaming\\\/retro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/gaming\\\/retro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/www.senses.se\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gaming\",\"item\":\"https:\\\/\\\/www.senses.se\\\/en\\\/gaming\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Retro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.senses.se\\\/en\\\/\",\"name\":\"Senses\",\"description\":\"Entertainment and lifestyle for all your senses.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.senses.se\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/#organization\",\"name\":\"Senses\",\"url\":\"https:\\\/\\\/www.senses.se\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.senses.se\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/senses-logo-600.webp\",\"contentUrl\":\"https:\\\/\\\/www.senses.se\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/senses-logo-600.webp\",\"width\":600,\"height\":182,\"caption\":\"Senses\"},\"image\":{\"@id\":\"https:\\\/\\\/www.senses.se\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"publishingPrinciples\":\"https:\\\/\\\/www.senses.se\\\/en\\\/how-we-rate-on-senses-se\\\/\",\"foundingDate\":\"2008\",\"about\":\"https:\\\/\\\/www.senses.se\\\/en\\\/about\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SensesSe\",\"https:\\\/\\\/x.com\\\/SensesSe\",\"https:\\\/\\\/www.instagram.com\\\/senses.se\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SensesSe\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retro-arkiv - Senses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.senses.se\/en\/gaming\/retro\/","og_locale":"en_US","og_type":"article","og_title":"Retro-arkiv - Senses","og_description":"Old games for old formats, for example Nintendo 8-bit (NES), Super Nintendo (SNES), Commodore Amiga, SEGA Mega Drive, arcade games and more.","og_url":"https:\/\/www.senses.se\/en\/gaming\/retro\/","og_site_name":"Senses","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.senses.se\/en\/gaming\/retro\/","url":"https:\/\/www.senses.se\/en\/gaming\/retro\/","name":"Retro-arkiv - Senses","isPartOf":{"@id":"https:\/\/www.senses.se\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.senses.se\/en\/gaming\/retro\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.senses.se\/en\/gaming\/retro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/www.senses.se\/en\/"},{"@type":"ListItem","position":2,"name":"Gaming","item":"https:\/\/www.senses.se\/en\/gaming\/"},{"@type":"ListItem","position":3,"name":"Retro"}]},{"@type":"WebSite","@id":"https:\/\/www.senses.se\/en\/#website","url":"https:\/\/www.senses.se\/en\/","name":"Senses","description":"Entertainment and lifestyle for all your senses.","publisher":{"@id":"https:\/\/www.senses.se\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.senses.se\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.senses.se\/en\/#organization","name":"Senses","url":"https:\/\/www.senses.se\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.senses.se\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.senses.se\/en\/wp-content\/uploads\/sites\/2\/2025\/05\/senses-logo-600.webp","contentUrl":"https:\/\/www.senses.se\/en\/wp-content\/uploads\/sites\/2\/2025\/05\/senses-logo-600.webp","width":600,"height":182,"caption":"Senses"},"image":{"@id":"https:\/\/www.senses.se\/en\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/www.senses.se\/en\/how-we-rate-on-senses-se\/","foundingDate":"2008","about":"https:\/\/www.senses.se\/en\/about\/","sameAs":["https:\/\/www.facebook.com\/SensesSe","https:\/\/x.com\/SensesSe","https:\/\/www.instagram.com\/senses.se\/","https:\/\/www.youtube.com\/c\/SensesSe"]}]}},"_links":{"self":[{"href":"https:\/\/www.senses.se\/en\/wp-json\/wp\/v2\/categories\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.senses.se\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.senses.se\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.senses.se\/en\/wp-json\/wp\/v2\/categories\/29"}],"wp:post_type":[{"href":"https:\/\/www.senses.se\/en\/wp-json\/wp\/v2\/posts?categories=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}